{"id":1871288,"date":"2026-05-08T10:20:03","date_gmt":"2026-05-08T08:20:03","guid":{"rendered":"https:\/\/www.vesterling.com\/job\/23407-it-administrator-sever-netzwerke-backup-support-ulm\/"},"modified":"2026-05-12T10:00:05","modified_gmt":"2026-05-12T08:00:05","slug":"23407-it-administrator-sever-netzwerke-backup-support-ulm","status":"publish","type":"job","link":"https:\/\/www.vesterling.com\/fr\/job\/23407-it-administrator-sever-netzwerke-backup-support-ulm\/","title":{"rendered":"IT Administrator | Sever, Netzwerke, Backup, Support | Inhouse (mwd)"},"content":{"rendered":"<h2>Als IT Administrator \u00fcbernehmen Sie Verantwortung f\u00fcr Konfiguration und Betrieb der IT-Infrastruktur.<\/h2>\n<h4>Skills<\/h4>\n<p>Sehr gute Kenntnisse in Windows-Umgebungen.<br \/>\nLinux-Kenntnisse sind ebenfalls w\u00fcnschenswert.<br \/>\nUmfassendes Wissen in den Bereichen Netzwerken LAN, WLAN und VPN.<br \/>\nErfahrung mit VM-Ware.<br \/>\nKenntnisse in der Administration von Exchange- und Terminal-Servern.<br \/>\nIdeal: Erfahrung zu Lizenzverwaltung sowie Hard- und Software-Beschaffung.<br \/>\nReisebereitschaft zwischen den Standorten innerhalb Deutschlands.<br \/>\nVon Vorteil: Kenntnisse im Umgang mit ERP-Systemen und mit der Buchhaltungssoftware DATEV.<br \/>\nGute Deutschkenntnisse.<\/p>\n<h4>Duties<\/h4>\n<p>Als IT Administrator \u00fcbernehmen Sie Verantwortung f\u00fcr Konfiguration und Betrieb der IT-Infrastruktur:<br \/>\nStandort\u00fcbergreifende Verantwortung f\u00fcr Konfiguration, Aufbau, Wartung und Betrieb von Clients und Servern sowie von Netzwerk, Datenbanken und zugeh\u00f6riger Infrastruktur.<br \/>\nSystem- und Daten-Backups.<br \/>\nSicherheit s\u00e4mtlicher Systeme.<br \/>\nUpdates und Dokumentation.<br \/>\nIT-Support f\u00fcr reibungslosen Arbeitsalltag im Betrieb.<br \/>\nKoordination externer Dienstleister und Systemh\u00e4user.<br \/>\nRealisierung interner IT-Projekte in Zusammenarbeit mit den Fachbereichen.<\/p>\n<h4>Clientdescription<\/h4>\n<p>Unser Klient ist ein international erfolgreicher Hersteller von Spezialfahrzeugen. Individuelle Weiterentwicklung und ein respektvolles Miteinander auf Augenh\u00f6he sind essenzieller Bestandteil der Firmenkultur.<\/p>\n<h4>Careerlevel<\/h4>\n<p>Ab 2 Jahre <\/p>\n<h4>Industrytags<\/h4>\n<p>Automotive,Ingenieurwesen<\/p>\n<h4>Dutytags<\/h4>\n<p>Client\/Server,Netzwerke<\/p>\n<h4>Travelrequirements<\/h4>\n<p>Max. gelegentliche \u00dcbernachtung<\/p>\n<h4>Salaryrange<\/h4>\n<p>45.000 \u20ac &#8211; 65.000 \u20ac<\/p>\n<h4>Publishedlocations<\/h4>\n<p>Ulm<\/p>\n<h4>Contract<\/h4>\n<p>Unbefristete Festanstellung<\/p>\n<h4>Contractverbose<\/h4>\n<p>Unbefristete Festanstellung&nbsp;durch unseren Klienten<\/p>\n<h4>Keywords<\/h4>\n<p>Windows,VPN,VMware Produkte,Server Virtualisierung,MS-SQL-DBA,MS Admin,Lokale Netzwerke,Linux \/ Unix Administration,IT-Infrastruktur-Support,Breitbandnetze<\/p>\n<h4>Metadescription<\/h4>\n<p>IT Administrator in Ulm. Vesterling AG. Einer der f\u00fchrenden Personaldienstleister im Bereich Technologie.<\/p>\n<h4>Metatitle<\/h4>\n<p>IT Administrator in Ulm<\/p>\n","protected":false},"template":"","class_list":["post-1871288","job","type-job","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.vesterling.com\/fr\/wp-json\/wp\/v2\/job\/1871288","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vesterling.com\/fr\/wp-json\/wp\/v2\/job"}],"about":[{"href":"https:\/\/www.vesterling.com\/fr\/wp-json\/wp\/v2\/types\/job"}],"wp:attachment":[{"href":"https:\/\/www.vesterling.com\/fr\/wp-json\/wp\/v2\/media?parent=1871288"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}